{"id":1549,"date":"2017-11-01T11:11:40","date_gmt":"2017-11-01T10:11:40","guid":{"rendered":"https:\/\/2017.cologne.wordcamp.org\/?p=1549"},"modified":"2017-10-31T15:38:09","modified_gmt":"2017-10-31T14:38:09","slug":"warm-up-die-koelsche-art","status":"publish","type":"post","link":"https:\/\/cologne.wordcamp.org\/2017\/warm-up-die-koelsche-art\/","title":{"rendered":"Warm Up &#8211; die k\u00f6lsche Art"},"content":{"rendered":"<p>Kein WordCamp ohne Party. Und da wir hier in K\u00f6ln ja bekanntlich \u00e4u\u00dferst &#8222;selten&#8220; feiern, \u00fcben wir schon einmal am Freitag:<\/p>\n<blockquote>\n<p>Wer nie e k\u00f6lsch Glas Wiess<br \/> un dann e Schnettche Kie\u00df<br \/> verzehrt h\u00e4t met Aptit,<br \/> der kennt dat Levve nit.<\/p>\n<p>Och wem die Name fremb, wie &#8222;Fr\u00fch&#8220; un &#8222;Schebens T\u00fcnn&#8220;<br \/> der muss wohl nit en K\u00f6lle he am Rhing jebore sin.<\/p>\n<\/blockquote>\n<p style=\"text-align: right\"><small>[<a href=\"http:\/\/www.kallendresser.de\/ostermann\/titel\/027.html\">Willy Ostermann, D\u00e4 mu\u00df nit he jebore sin<\/a>]<\/small><\/p>\n<p>\u00a0<\/p>\n<p>In diesem Sinne wollen wir mit allen, die bereits am Freitag Abend zum WordCamp anreisen, einen Ausflug in die K\u00f6lner Brauhaus-Kultur machen.<\/p>\n<p>Wir treffen uns am <strong>Freitag Abend um 19:00 Uhr<\/strong> im <a href=\"http:\/\/brauereizurmalzmuehle.de\/\"><strong>Brauhaus Zur Malzm\u00fchle<\/strong><\/a>, um uns bei <a href=\"http:\/\/brauereizurmalzmuehle.de\/menu-animated\/\">Himmel un \u00c4\u00e4d, Halven Hahn<\/a> und nat\u00fcrlichen dem einen oder anderen K\u00f6lsch kennen zu lernen, nette Gespr\u00e4che zu f\u00fchren und uns auf das WordCamp einzustimmen.<\/p>\n<p>Wichtig: Wir haben in der Brauerei einen Raum in der ersten Etage f\u00fcr uns reserviert. Da die Malzm\u00fchle an den Wochenenden stark frequentiert ist, werden die Tische, die um 20:15 Uhr immer noch frei sind, vom Brauhaus f\u00fcr ihre wartenden G\u00e4ste freigegeben. Kommt also bitte m\u00f6glichst fr\u00fch!<\/p>\n<p>Wir freuen uns auf viele interessante Gespr\u00e4che und einen geselligen Abend mit Euch in einem urigen k\u00f6lschen Brauhaus:<\/p>\n<h3>#WCCGN WarmUp Party<\/h3>\n<p>Freitag, 17. November 2017, ab 19:00 Uhr<br \/> Brauhaus Zur Malzm\u00fchle<br \/> Heumarkt 6, 50667 K\u00f6ln<\/p>\n<p>\u00a0<\/p>\n<div class=\"googlemaps\">\n\t\t\t\t<iframe loading=\"lazy\" width=\"800\" height=\"600\" frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\"  src=\"https:\/\/www.google.com\/maps\/embed?pb=%211m18%211m12%211m3%211d2514.4055932293013%212d6.95834861510852%213d50.93471176023462%212m3%211f0%212f0%213f0%213m2%211i1024%212i768%214f13.1%213m3%211m2%211s0x47bf25b3c67b7e5d%3A0xac20833db1cab65f%212sBrauerei%20zur%20Malzm%C3%BChle%215e0%213m2%211sde%212sde%214v1509293229080\"><\/iframe>\n\t\t\t<\/div>\n<p>\u00a0<\/p>\n<p>Das Brauhaus Zur Malzm\u00fchle liegt verkehrsg\u00fcnstig am Heumarkt:<\/p>\n<ul>\n<li>Wer <strong>mit dem Auto<\/strong> kommt, findet einen Parkplatz in der <a href=\"http:\/\/www.contipark.de\/de-DE\/find-parking\/koeln-tiefgarage-heumarkt\/\">Tiefgarage Heumarkt<\/a><br \/> (Einfahrt f\u00fcr&#8217;s Navi: Markmannsgasse 3, 50667 K\u00f6ln).<\/li>\n<li>Oder Ihr fahrt <strong>mit der U-Bahn oder Stadtbahn<\/strong> (Linien 1, 5, 7 und 9) bis zum Heumarkt. Der U-Bahnhof der Linie 5 liegt unter dem Heumarkt, die Linien 1, 7\u00a0 und 9 halten direkt auf dem Heumarkt. Von dort sind es ca. 250m &#8211; einmal quer \u00fcber den Heumarkt &#8211; bis zur Brauerei Zur Malzm\u00fchle.<\/li>\n<\/ul>\n<p><strong>Seine Zeche zahlt am Freitag Abend jeder selbst.<\/strong><\/p>\n<p>Wir freuen uns auf einen netten Abend mit Euch, an dessen Ende auch Ihr sagen k\u00f6nnt: <a href=\"http:\/\/www.spiegel.de\/wirtschaft\/staatsbesuch-ich-bin-ein-koelsch-a-27712.html\">&#8222;Ich bin ein K\u00f6lsch&#8220;<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kein WordCamp ohne Party. Und da wir hier in K\u00f6ln ja bekanntlich \u00e4u\u00dferst &#8222;selten&#8220; feiern, \u00fcben wir schon einmal am Freitag: Wer nie e k\u00f6lsch Glas Wiess un dann e Schnettche Kie\u00df verzehrt h\u00e4t met Aptit, der kennt dat Levve nit. Och wem die Name fremb, wie &#8222;Fr\u00fch&#8220; un &#8222;Schebens T\u00fcnn&#8220; der muss wohl nit [&hellip;]<\/p>\n","protected":false},"author":14244452,"featured_media":1559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[1175024],"tags":[280,499001],"class_list":["post-1549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten-vom-wordcamp-cologne","tag-party","tag-warmup"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pheMQk-oZ","jetpack_featured_media_url":"https:\/\/cologne.wordcamp.org\/2017\/files\/2017\/11\/Brauerei_zur_Malzm\u00fchle_K\u00f6ln-1917.jpg","_links":{"self":[{"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts\/1549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/users\/14244452"}],"replies":[{"embeddable":true,"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/comments?post=1549"}],"version-history":[{"count":15,"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts\/1549\/revisions"}],"predecessor-version":[{"id":1629,"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/posts\/1549\/revisions\/1629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/media\/1559"}],"wp:attachment":[{"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/media?parent=1549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/categories?post=1549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cologne.wordcamp.org\/2017\/wp-json\/wp\/v2\/tags?post=1549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}